{"id":5232,"date":"2025-09-08T21:14:28","date_gmt":"2025-09-08T19:14:28","guid":{"rendered":"https:\/\/implementi.ai\/en\/2025\/09\/08\/gemini-app-now-supports-audio-files\/"},"modified":"2025-09-08T21:14:28","modified_gmt":"2025-09-08T19:14:28","slug":"la-aplicacion-gemini-ya-admite-archivos-de-audio","status":"publish","type":"post","link":"https:\/\/implementi.ai\/es\/2025\/09\/08\/gemini-app-now-supports-audio-files\/","title":{"rendered":"La aplicaci\u00f3n Gemini ya admite archivos de audio"},"content":{"rendered":"<h2>Importantes actualizaciones de los productos de Google basados en Gemini<\/h2>\n<p>Google, l\u00edder en servicios y productos digitales, acaba de anunciar tres importantes actualizaciones de su lista de productos basados en Gemini. Estas mejoras se manifiestan en la capacidad de la aplicaci\u00f3n Gemini para aceptar archivos de audio; la nueva capacidad de B\u00fasqueda para manejar cinco idiomas adicionales; y la novedosa iniciativa de creaci\u00f3n de entradas de blog, gu\u00edas de estudio, avisos y cuestionarios de NotebookLM.<\/p>\n<p>Profundicemos en estas actualizaciones para apreciar c\u00f3mo cambiar\u00edan la experiencia del usuario.<\/p>\n<h2>Compatibilidad de los archivos de audio con Gemini<\/h2>\n<p>Seg\u00fan Josh Woodward, Vicepresidente de Google Labs y Gemini, la principal petici\u00f3n de los usuarios era que la aplicaci\u00f3n Gemini aceptara archivos de audio. Una vez concedida esta petici\u00f3n, los usuarios gratuitos de la aplicaci\u00f3n Gemini pueden disfrutar ahora de un l\u00edmite de audio de diez minutos. Tambi\u00e9n hay un l\u00edmite de cinco avisos gratuitos al d\u00eda. Sin embargo, los usuarios con AI Pro o AI Ultra pueden subir archivos de audio de hasta tres horas de duraci\u00f3n. Adem\u00e1s de dar cabida a varios formatos de archivo, cada pregunta de Gemini puede manejar hasta diez archivos, incluidos los que est\u00e1n dentro de archivos ZIP.<\/p>\n<h2>Cinco nuevos idiomas para el modo AI de Google Search<\/h2>\n<p>En el \u00e1mbito del Modo AI de la B\u00fasqueda de Google, se han introducido cinco opciones ling\u00fc\u00edsticas adicionales, a saber, hindi, indonesio, japon\u00e9s, coreano y portugu\u00e9s de Brasil. Esta novedad ha sido posible gracias a la integraci\u00f3n de Gemini 2.5 con la funci\u00f3n de B\u00fasqueda. El objetivo es que m\u00e1s personas puedan hacer preguntas complejas en su lengua materna, al tiempo que exploran la web con mayor profundidad.<\/p>\n<h2>Actualizaci\u00f3n del software de NotebookLM<\/h2>\n<p>NotebookLM, otro miembro de la familia Gemini, tambi\u00e9n recibe una actualizaci\u00f3n. Este software ofrece ahora nuevos estilos de informes en m\u00e1s de 80 idiomas. Esta funci\u00f3n se basa en los documentos, archivos y otros soportes cargados por el usuario. Los formatos de informe est\u00e1ndar que se est\u00e1n implementando incluyen gu\u00edas de estudio, documentos informativos y blogs. La actualizaci\u00f3n tambi\u00e9n incluye flashcards y cuestionarios, ofreciendo as\u00ed a los usuarios un completo kit de herramientas para sus tareas digitales.<\/p>\n<p>Cabe se\u00f1alar que los usuarios pueden personalizar la estructura, el tono y el estilo de sus informes. Esta actualizaci\u00f3n de software deber\u00eda estar totalmente disponible a finales de semana.<\/p>\n<p>El mes pasado, Google lanz\u00f3 una avalancha de funciones relacionadas con la inteligencia artificial. A partir de agosto, Gemini, el software basado en IA, empez\u00f3 a recordar autom\u00e1ticamente los datos y preferencias del usuario de conversaciones anteriores. Ese mismo mes, los usuarios gratuitos obtuvieron acceso al software de generaci\u00f3n de v\u00eddeo de Workspace, Vids. A esto le sigui\u00f3 una actualizaci\u00f3n de Fotos, que permite crear v\u00eddeos silenciosos de 4 segundos de duraci\u00f3n a partir de las fotograf\u00edas personales de los usuarios.<\/p>\n<p>Este giro hacia las actualizaciones relacionadas con la IA demuestra el compromiso de Google de acelerar la fusi\u00f3n de la inteligencia humana con las capacidades de la IA. Los usuarios deber\u00edan prepararse para experiencias m\u00e1s inmersivas e intuitivas a medida que la IA siga aumentando y redefiniendo nuestras realidades digitales.<\/p>\n<p><b>Art\u00edculo original: <a href=\"https:\/\/www.theverge.com\/ai-artificial-intelligence\/774008\/gemini-audio-new-languages-notebooklm-reports\" target=\"_blank\" rel=\"noopener\">The Verge<\/a><\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>Major Updates to Google&#8217;s Gemini-powered Products Google, a leader in digital services and products, just announced three major updates to its Gemini-powered roster. These improvements manifest in the Gemini app&#8217;s ability to accept audio files; Search&#8217;s new capability to handle five additional languages; and NotebookLM&#8217;s novel blog posts, study guides, warnings and quizzes creation initiative. Let&#8217;s delve deeper into these [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5233,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[],"class_list":["post-5232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio"],"featured_image_src":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/09\/5232-1024x683.png","blog_images":{"medium":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/09\/5232-300x200.png","large":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/09\/5232-1024x683.png"},"ams_acf":[],"jetpack_featured_media_url":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/09\/5232.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/posts\/5232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/comments?post=5232"}],"version-history":[{"count":0,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/posts\/5232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/media\/5233"}],"wp:attachment":[{"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/media?parent=5232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/categories?post=5232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/tags?post=5232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}