{"id":6476,"date":"2026-03-20T19:17:02","date_gmt":"2026-03-20T18:17:02","guid":{"rendered":"https:\/\/implementi.ai\/en\/2026\/03\/20\/trump-attempts-to-dismantle-state-ai-regulations-again\/"},"modified":"2026-03-20T19:17:02","modified_gmt":"2026-03-20T18:17:02","slug":"trump-vuelve-a-intentar-desmantelar-la-normativa-estatal-sobre-ai","status":"publish","type":"post","link":"https:\/\/implementi.ai\/es\/2026\/03\/20\/trump-attempts-to-dismantle-state-ai-regulations-again\/","title":{"rendered":"Trump vuelve a intentar desmantelar la normativa estatal sobre IA."},"content":{"rendered":"<p>&lt;h1&gt;La visi&oacute;n de la Administraci&oacute;n Trump sobre la regulaci&oacute;n de la IA&lt;\/h1&gt;<\/p>\n<p>A finales de la semana pasada, la administraci&oacute;n Trump dio a conocer su nueva &lt;a href=&quot;&rdquo;https:\/\/www.whitehouse.gov\/wp-content\/uploads\/2026\/03\/03.20.26-National-Policy-Framework-for-Artificial-Intelligence-Legislative-Recommendations.pdf&rdquo;&quot;&gt;marco&lt;\/a&gt; sobre c&oacute;mo cree que deber&iacute;a desarrollarse la regulaci&oacute;n de la inteligencia artificial (IA). Este plan de siete puntos adopt&oacute; una postura bastante audaz, argumentando esencialmente que el papel del gobierno federal en el mundo de la regulaci&oacute;n de la IA debe ser m&iacute;nimo, m&aacute;s all&aacute; de las normas espec&iacute;ficamente orientadas a la seguridad de los ni&ntilde;os.<\/p>\n<p>Uno de los principales hilos conductores de este plan es el deseo de no ahogar la innovaci\u00f3n. El plan advierte contra todo lo que impida la \u2018estrategia nacional para lograr el dominio mundial de la IA\u2019. En el fondo, este plan parece tratar de c\u00f3mo mantener la ventaja competitiva de Estados Unidos en el mundo de la tecnolog\u00eda de IA.<\/p>\n<p>&lt;h2&gt;Seguridad infantil y gastos de electricidad&lt;\/h2&gt;<br \/>\nUno de los \u00e1mbitos que este marco se\u00f1ala para un enfoque gubernamental m\u00e1s intervencionista es la protecci\u00f3n de los menores. El plan insta al Congreso a tomar medidas que garanticen salvaguardias adicionales para los ni\u00f1os que utilizan servicios de IA.<\/p>\n<p>Otro aspecto interesante de este plan es el aumento de los costes de la electricidad debido a la infraestructura de IA. El plan aconseja al Congreso que tome medidas para evitar un repunte de estos gastos, aunque no se detalla expl\u00edcitamente el camino a seguir para lograrlo.<\/p>\n<p>Parece que este enfoque vago era un tema recurrente del marco, sobre todo cuando se trataba de estimular el \u2018desarrollo de la juventud y la formaci\u00f3n de habilidades\u2019. El objetivo est\u00e1 claro: aumentar la familiaridad de los j\u00f3venes con las herramientas de IA, pero la forma de conseguirlo queda bastante abierta.<\/p>\n<p>El enfoque de la administraci\u00f3n Trump respecto a la regulaci\u00f3n de la IA es claro: creen que el gobierno federal debe ceder en gran medida a las fuerzas de la innovaci\u00f3n, al tiempo que garantiza salvaguardas para nuestros ciudadanos m\u00e1s j\u00f3venes y vulnerables. Ni que decir tiene que los pr\u00f3ximos a\u00f1os ser\u00e1n interesantes a medida que veamos c\u00f3mo se pone en marcha este marco y el impacto que tiene en el sector de la IA.<\/p>\n<p>Con el debate sobre la regulaci\u00f3n de la IA a punto de aumentar, este marco establece la posici\u00f3n de la administraci\u00f3n Trump al respecto. Solo el tiempo dir\u00e1 c\u00f3mo afectar\u00e1 este enfoque a la industria y si cumple el doble objetivo de proteger a los ciudadanos y mantener el dominio de Estados Unidos sobre la IA.<\/p>\n<p>&lt;p&gt;Fuente: &lt;a href=&quot;\/es\/&rdquo;https:\/\/www.theverge.com\/ai-artificial-intelligence\/898055\/trump-new-ai-policy-framework&rdquo;\/&quot;&gt;The Verge&lt;\/a&gt;&lt;\/p&gt;<\/p>","protected":false},"excerpt":{"rendered":"<p>&lt;h1&gt;The Trump Administration&#8217;s Vision for AI Regulation&lt;\/h1&gt; Late last week, the Trump administration unveiled its new &lt;a href=&#8221;https:\/\/www.whitehouse.gov\/wp-content\/uploads\/2026\/03\/03.20.26-National-Policy-Framework-for-Artificial-Intelligence-Legislative-Recommendations.pdf&#8221;&gt;framework&lt;\/a&gt; for how it thinks artificial intelligence (AI) regulation should unfold. This seven-point game plan took a pretty bold stance &#8211; essentially arguing that the federal government&#8217;s role in the world of AI regulation should be minimal, beyond rules specifically geared towards the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6477,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[26],"tags":[],"class_list":["post-6476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-automation"],"featured_image_src":"https:\/\/implementi.ai\/wp-content\/uploads\/2026\/03\/6476-1024x683.jpg","blog_images":{"medium":"https:\/\/implementi.ai\/wp-content\/uploads\/2026\/03\/6476-300x200.jpg","large":"https:\/\/implementi.ai\/wp-content\/uploads\/2026\/03\/6476-1024x683.jpg"},"ams_acf":[],"jetpack_featured_media_url":"https:\/\/implementi.ai\/wp-content\/uploads\/2026\/03\/6476.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/posts\/6476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/comments?post=6476"}],"version-history":[{"count":0,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/posts\/6476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/media\/6477"}],"wp:attachment":[{"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/media?parent=6476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/categories?post=6476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/implementi.ai\/es\/wp-json\/wp\/v2\/tags?post=6476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}