{"id":4302,"date":"2025-08-15T21:19:07","date_gmt":"2025-08-15T19:19:07","guid":{"rendered":"https:\/\/implementi.ai\/2025\/08\/15\/this-researcher-modified-openais-open-weights-model-gpt-oss-20b-transforming-it-into-a-non-reasoning-base-model-with-reduced-alignment-and-increased-freedom\/"},"modified":"2025-08-29T11:54:43","modified_gmt":"2025-08-29T09:54:43","slug":"ce-chercheur-a-modifie-le-modele-de-poids-ouvert-openais-gpt-oss-20b-en-le-transformant-en-un-modele-de-base-non-raisonne-avec-un-alignement-reduit-et-une-liberte-accrue","status":"publish","type":"post","link":"https:\/\/implementi.ai\/fr\/2025\/08\/15\/this-researcher-modified-openais-open-weights-model-gpt-oss-20b-transforming-it-into-a-non-reasoning-base-model-with-reduced-alignment-and-increased-freedom\/","title":{"rendered":"Le mod\u00e8le de poids ouvert modifi\u00e9 de l'OpenAI, gpt-oss-20b, est un mod\u00e8le de base non raisonn\u00e9 avec un alignement r\u00e9duit."},"content":{"rendered":"<p>Dans le monde de l'IA, qui \u00e9volue rapidement, la relation dynamique entre l'originalit\u00e9 et l'imitation est fr\u00e9quemment mise \u00e0 l'\u00e9preuve. Une r\u00e9v\u00e9lation r\u00e9cente vient \u00e9tayer ce point de vue : un chercheur nomm\u00e9 Morris a conclu que l'IA pouvait \u00e9galement reproduire des passages pr\u00e9cis d'\u0153uvres prot\u00e9g\u00e9es par le droit d'auteur. Son exp\u00e9rience a port\u00e9 sur six extraits de livres, dont trois ont \u00e9t\u00e9 reproduits exactement par l'IA.<\/p>\n<p>Morris a adopt\u00e9 un mod\u00e8le fond\u00e9 sur le mod\u00e8le de poids ouvert d'OpenAI, GPT- OSS 20b, et l'a \u00e9tonnamment modifi\u00e9 en un mod\u00e8le de base qui pr\u00e9sente moins d'alignement mais une plus grande libert\u00e9. Ce projet refl\u00e8te la v\u00e9ritable flexibilit\u00e9 et capacit\u00e9 de l'IA et la mani\u00e8re dont elle peut \u00eatre r\u00e9gl\u00e9e pour atteindre des r\u00e9sultats auparavant consid\u00e9r\u00e9s comme inimaginables.<\/p>\n<h2>L'exp\u00e9rience<\/h2>\n<p>Afin de tester les capacit\u00e9s de reproduction de l'IA, Morris a men\u00e9 une s\u00e9rie d'exp\u00e9riences portant sur des documents prot\u00e9g\u00e9s par le droit d'auteur. Sur les six extraits de livres utilis\u00e9s dans l'enqu\u00eate, il a \u00e9t\u00e9 constat\u00e9 que l'IA pouvait en reproduire trois mot pour mot. Ce r\u00e9sultat, bien qu'impressionnant d'un point de vue technologique, pr\u00e9sente de nombreuses complications juridiques et \u00e9thiques, suscitant un d\u00e9bat plus large sur l'impact de l'IA sur nos ressources.<\/p>\n<p>Le cadre d'IA utilis\u00e9 ici m\u00e9rite d'\u00eatre mentionn\u00e9 car il souligne le succ\u00e8s de la reproduction. Le mod\u00e8le de base, GPT-OSS 20b, a \u00e9t\u00e9 transform\u00e9 par Morris en un mod\u00e8le moins align\u00e9 mais plus lib\u00e9ral, d\u00e9montrant ainsi les capacit\u00e9s \u00e9lastiques de l'IA. Bien qu'il n'ait pas raisonn\u00e9 comme le ferait un \u00eatre humain, il a fourni des r\u00e9ponses incroyables qui \u00e9taient un fac-simil\u00e9 fiable du texte original.<\/p>\n<h2>Implications et avenir<\/h2>\n<p>Il convient de noter que cela pose des probl\u00e8mes concrets dans le contexte de la r\u00e9glementation des droits d'auteur et des protections dont b\u00e9n\u00e9ficient les \u0153uvres \u00e9crites. Comment faire en sorte que l'IA les respecte et les fasse respecter ? Si les prouesses technologiques de l'IA sont impressionnantes, elles soulignent \u00e9galement l'importance d'\u00e9tablir un cadre \u00e9thique solide pour l'utilisation de l'IA.<\/p>\n<p>Pour les cr\u00e9ateurs de contenu de divers m\u00e9dias, cela peut \u00eatre le signe d'un changement imminent. L'id\u00e9e d'une IA reproduisant mot pour mot leur travail original peut \u00eatre d\u00e9concertante. D'un autre c\u00f4t\u00e9, cela pourrait-il ouvrir la voie \u00e0 une \u00e8re o\u00f9 l'IA aiderait les cr\u00e9ateurs de contenu \u00e9crit, en produisant des premi\u00e8res \u00e9bauches ou m\u00eame des copies finales avec une rapidit\u00e9 et une pr\u00e9cision sans pr\u00e9c\u00e9dent ?<\/p>\n<p>Cette r\u00e9v\u00e9lation r\u00e9affirme l'\u00e9quilibre d\u00e9licat entre les droits, les r\u00e8gles et l'innovation qui marque le paysage de l'IA. Les conclusions de Morris constituent un rappel important et contribuent \u00e0 la conversation embl\u00e9matique sur les capacit\u00e9s des machines, ainsi que sur les implications \u00e9thiques et juridiques de leur utilisation dans notre monde de plus en plus num\u00e9rique.<\/p>\n<p>Article original : <a href=\"https:\/\/venturebeat.com\/ai\/this-researcher-turned-openais-open-weights-model-gpt-oss-20b-into-a-non-reasoning-base-model-with-less-alignment-more-freedom\/\" target=\"_blank\" rel=\"noopener\">https:\/\/venturebeat.com\/ai\/this-researcher-turned-openais-open-weights-model-gpt-oss-20b-into-a-non-reasoning-base-model-with-less-alignment-more-freedom\/<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>In the rapidly evolving world of AI, the dynamic relation between originality and imitation is frequently tested. A recent revelation supports this view, as driven by a researcher named Morris, who concluded that AI can also replicate precise passages from copyrighted works. His experiment involved six book excerpts, out of which AI could reproduce three exactly. Morris adopted a model [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[26],"tags":[],"class_list":["post-4302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-automation"],"featured_image_src":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/08\/4302-1024x683.png","blog_images":{"medium":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/08\/4302-300x200.png","large":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/08\/4302-1024x683.png"},"ams_acf":[],"jetpack_featured_media_url":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/08\/4302.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/posts\/4302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/comments?post=4302"}],"version-history":[{"count":1,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/posts\/4302\/revisions"}],"predecessor-version":[{"id":4904,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/posts\/4302\/revisions\/4904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/media\/4303"}],"wp:attachment":[{"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/media?parent=4302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/categories?post=4302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/tags?post=4302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}