{"id":5753,"date":"2025-10-15T16:03:33","date_gmt":"2025-10-15T14:03:33","guid":{"rendered":"https:\/\/implementi.ai\/en\/2025\/10\/15\/japan-urges-openai-to-stop-using-manga-and-anime-without-permission\/"},"modified":"2025-10-15T16:03:33","modified_gmt":"2025-10-15T14:03:33","slug":"le-japon-demande-a-lopenai-de-cesser-dutiliser-des-mangas-et-des-dessins-animes-sans-autorisation","status":"publish","type":"post","link":"https:\/\/implementi.ai\/fr\/2025\/10\/15\/japan-urges-openai-to-stop-using-manga-and-anime-without-permission\/","title":{"rendered":"Le Japon demande \u00e0 OpenAI de cesser d'utiliser des mangas et des dessins anim\u00e9s sans autorisation"},"content":{"rendered":"<div>\n<p>Suite \u00e0 une controverse, OpenAI se retrouve une fois de plus sous le microscope. Cette fois, c'est le gouvernement japonais qui s'oppose \u00e0 la fa\u00e7on dont OpenAI utilise les \u0153uvres d'art japonaises et lui demande officiellement d'y mettre un terme. L'histoire, initialement rapport\u00e9e par <em>ITMedia<\/em> et rapport\u00e9 par la suite par <em>IGN<\/em>La Commission europ\u00e9enne a annonc\u00e9 que l'intelligence artificielle (IA) de l'application vid\u00e9o sociale de l'entreprise, Sora, avait g\u00e9n\u00e9r\u00e9 des contenus douteux qui semblaient copier, ou \"imiter\", des \u0153uvres d'art japonaises.<\/p>\n<p>C'est Minoru Kiuchi, un ministre chevronn\u00e9 du gouvernement japonais qui assume une multitude de responsabilit\u00e9s, dont la moindre n'est pas la strat\u00e9gie du pays en mati\u00e8re de propri\u00e9t\u00e9 intellectuelle, qui a formul\u00e9 l'admonestation publique des actions d'OpenAI. Selon lui, les animes, les mangas et autres expressions artistiques connexes sont des \"tr\u00e9sors irrempla\u00e7ables\" et il a pris la d\u00e9cision de demander officiellement \u00e0 OpenAI de mettre fin \u00e0 son comportement illicite.<\/p>\n<p>Tout ceci intervient au milieu d'une p\u00e9riode que l'on peut qualifier de tumultueuse pour l'entreprise am\u00e9ricaine. Elle a r\u00e9cemment \u00e9t\u00e9 confront\u00e9e \u00e0 des r\u00e9actions n\u00e9gatives \u00e0 la suite de la mise en \u0153uvre, puis de l'abandon, d'une politique d'exclusion des d\u00e9tenteurs de droits d'auteur sur sa plateforme Sora. OpenAI reconna\u00eet sans aucun doute les prouesses cr\u00e9atives des artistes japonais, comme l'a laiss\u00e9 entendre le PDG de la soci\u00e9t\u00e9, Sam Altman. Il a d\u00e9clar\u00e9 publiquement que l'entreprise avait une dette envers le Japon pour sa \"remarquable production cr\u00e9ative\". Il est int\u00e9ressant de noter que le g\u00e9n\u00e9rateur d'images d'OpenAI avait pr\u00e9c\u00e9demment inond\u00e9 l'internet d'une foule d'images qui ressemblaient \u00e9trangement aux \u0153uvres du c\u00e9l\u00e8bre Studio Ghibli.<\/p>\n<p>L'avenir est peut-\u00eatre incertain pour OpenAI en termes d'image publique, en particulier compte tenu des r\u00e9centes turbulences. Avec les pressions exerc\u00e9es par le gouvernement japonais et la surveillance accrue des d\u00e9tenteurs de droits d'auteur, il semble que l'entreprise doive relever un d\u00e9fi de taille. Pour naviguer dans ces eaux tendues, il faudra des compromis, des inventions ing\u00e9nieuses et un profond respect des droits des artistes partout dans le monde, en particulier au Japon. Seul l'avenir nous dira si OpenAI parviendra \u00e0 rem\u00e9dier \u00e0 la situation et \u00e0 att\u00e9nuer les critiques dont elle fait actuellement l'objet.<\/p>\n<p>Pour plus de d\u00e9tails sur cette affaire en cours, vous pouvez consulter l'article original <a href=\"https:\/\/www.theverge.com\/news\/799938\/japan-government-openai-sora\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Hot on the heels of some controversy, OpenAI has once again found itself under the microscope. This time, it&#8217;s the Japanese government that has taken issue with the way OpenAI has been utilizing Japanese artwork and has formalized a request for them to put a stop to it. The story, originally broken by ITMedia and subsequently reported by IGN, cited [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5754,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[],"class_list":["post-5753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-images"],"featured_image_src":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/10\/5753-1024x683.png","blog_images":{"medium":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/10\/5753-300x200.png","large":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/10\/5753-1024x683.png"},"ams_acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/implementi.ai\/wp-content\/uploads\/2025\/10\/5753.png","_links":{"self":[{"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/posts\/5753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/comments?post=5753"}],"version-history":[{"count":0,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/posts\/5753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/media\/5754"}],"wp:attachment":[{"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/media?parent=5753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/categories?post=5753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/implementi.ai\/fr\/wp-json\/wp\/v2\/tags?post=5753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}